{"id":10413,"date":"2023-08-24T20:46:23","date_gmt":"2023-08-25T01:46:23","guid":{"rendered":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/08\/Jasper8-22-2.jpg"},"modified":"2023-08-24T20:46:23","modified_gmt":"2023-08-25T01:46:23","slug":"jasper8-22-2","status":"inherit","type":"attachment","link":"https:\/\/www.debslunch.com\/blog\/jasper8-22-2\/","title":{"rendered":"Jasper8-22-2"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":{"0":"entry","1":"attachment","2":"publish","3":"author-ds83473gmail-com","4":"post-10413","6":"status-inherit"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/08\/Jasper8-22-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"338\" height=\"450\" src=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/08\/Jasper8-22-2-338x450.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/08\/Jasper8-22-2-338x450.jpg 338w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/08\/Jasper8-22-2-113x150.jpg 113w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/08\/Jasper8-22-2.jpg 488w\" sizes=\"auto, (max-width: 338px) 100vw, 338px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" data-url=https:\/\/www.debslunch.com\/blog\/jasper8-22-2\/><\/div>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":488,"height":650,"file":"2023\/08\/Jasper8-22-2.jpg","filesize":421988,"sizes":{"medium":{"file":"Jasper8-22-2-338x450.jpg","width":338,"height":450,"filesize":127945,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/08\/Jasper8-22-2-338x450.jpg"},"thumbnail":{"file":"Jasper8-22-2-113x150.jpg","width":113,"height":150,"filesize":27854,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/08\/Jasper8-22-2-113x150.jpg"},"full":{"file":"Jasper8-22-2.jpg","width":488,"height":650,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/08\/Jasper8-22-2.jpg"}},"image_meta":{"aperture":"1.5","credit":"","camera":"iPhone 14 Plus","caption":"","created_timestamp":"1692709204","copyright":"","focal_length":"5.7","iso":"250","shutter_speed":"0.016666666666667","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/08\/Jasper8-22-2.jpg","_links":{"self":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media\/10413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/comments?post=10413"}]}}