{"id":10613,"date":"2023-10-01T16:10:53","date_gmt":"2023-10-01T21:10:53","guid":{"rendered":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/Jasper9-20fave.jpg"},"modified":"2023-10-01T16:13:30","modified_gmt":"2023-10-01T21:13:30","slug":"jasper9-20fave","status":"inherit","type":"attachment","link":"https:\/\/www.debslunch.com\/blog\/2023\/10\/02\/the-rest-of-september-after-tiff\/jasper9-20fave\/","title":{"rendered":"Jasper9-20fave"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":{"0":"entry","1":"attachment","2":"publish","3":"author-ds83473gmail-com","4":"post-10613","6":"status-inherit"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/Jasper9-20fave.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"338\" height=\"450\" src=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/Jasper9-20fave-338x450.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/Jasper9-20fave-338x450.jpg 338w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/Jasper9-20fave-113x150.jpg 113w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/Jasper9-20fave.jpg 488w\" sizes=\"auto, (max-width: 338px) 100vw, 338px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Blurry but happy boy<\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" data-url=https:\/\/www.debslunch.com\/blog\/2023\/10\/02\/the-rest-of-september-after-tiff\/jasper9-20fave\/><\/div>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":488,"height":650,"file":"2023\/10\/Jasper9-20fave.jpg","filesize":216174,"sizes":{"medium":{"file":"Jasper9-20fave-338x450.jpg","width":338,"height":450,"filesize":70711,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/Jasper9-20fave-338x450.jpg"},"thumbnail":{"file":"Jasper9-20fave-113x150.jpg","width":113,"height":150,"filesize":22313,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/Jasper9-20fave-113x150.jpg"},"full":{"file":"Jasper9-20fave.jpg","width":488,"height":650,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/Jasper9-20fave.jpg"}},"image_meta":{"aperture":"1.5","credit":"","camera":"iPhone 14 Plus","caption":"","created_timestamp":"1695201593","copyright":"","focal_length":"5.7","iso":"800","shutter_speed":"0.041666666666667","title":"","orientation":"1","keywords":[]}},"post":10606,"source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/Jasper9-20fave.jpg","_links":{"self":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media\/10613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/comments?post=10613"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":10606,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/posts\/10606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}