{"id":10767,"date":"2023-10-31T13:45:29","date_gmt":"2023-10-31T18:45:29","guid":{"rendered":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/2023-10-25Jasper6.jpg"},"modified":"2023-10-31T13:45:29","modified_gmt":"2023-10-31T18:45:29","slug":"2023-10-25jasper6","status":"inherit","type":"attachment","link":"https:\/\/www.debslunch.com\/blog\/2023\/10\/31\/not-really-a-retired-persons-schedule\/2023-10-25jasper6\/","title":{"rendered":"2023-10-25Jasper6"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":{"0":"entry","1":"attachment","2":"publish","3":"author-ds83473gmail-com","4":"post-10767","6":"status-inherit"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/2023-10-25Jasper6.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"338\" height=\"450\" src=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/2023-10-25Jasper6-338x450.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/2023-10-25Jasper6-338x450.jpg 338w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/2023-10-25Jasper6-113x150.jpg 113w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/2023-10-25Jasper6.jpg 488w\" sizes=\"auto, (max-width: 338px) 100vw, 338px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" data-url=https:\/\/www.debslunch.com\/blog\/2023\/10\/31\/not-really-a-retired-persons-schedule\/2023-10-25jasper6\/><\/div>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":488,"height":650,"file":"2023\/10\/2023-10-25Jasper6.jpg","filesize":284431,"sizes":{"medium":{"file":"2023-10-25Jasper6-338x450.jpg","width":338,"height":450,"filesize":95579,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/2023-10-25Jasper6-338x450.jpg"},"thumbnail":{"file":"2023-10-25Jasper6-113x150.jpg","width":113,"height":150,"filesize":28539,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/2023-10-25Jasper6-113x150.jpg"},"full":{"file":"2023-10-25Jasper6.jpg","width":488,"height":650,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/2023-10-25Jasper6.jpg"}},"image_meta":{"aperture":"1.5","credit":"","camera":"iPhone 14 Plus","caption":"","created_timestamp":"1698226740","copyright":"","focal_length":"5.7","iso":"320","shutter_speed":"0.016666666666667","title":"","orientation":"1","keywords":[]}},"post":10761,"source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2023\/10\/2023-10-25Jasper6.jpg","_links":{"self":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media\/10767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/comments?post=10767"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":10761,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/posts\/10761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}