{"id":11807,"date":"2024-04-30T16:17:45","date_gmt":"2024-04-30T21:17:45","guid":{"rendered":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/04\/Jasper2024-04-26.jpg"},"modified":"2024-04-30T16:17:45","modified_gmt":"2024-04-30T21:17:45","slug":"jasper2024-04-26","status":"inherit","type":"attachment","link":"https:\/\/www.debslunch.com\/blog\/2024\/05\/02\/organizing\/jasper2024-04-26\/","title":{"rendered":"Jasper2024-04-26"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":{"0":"entry","1":"attachment","2":"publish","3":"author-ds83473gmail-com","4":"post-11807","6":"status-inherit"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/04\/Jasper2024-04-26.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"338\" height=\"450\" src=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/04\/Jasper2024-04-26-338x450.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/04\/Jasper2024-04-26-338x450.jpg 338w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/04\/Jasper2024-04-26-113x150.jpg 113w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/04\/Jasper2024-04-26.jpg 488w\" sizes=\"auto, (max-width: 338px) 100vw, 338px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" data-url=https:\/\/www.debslunch.com\/blog\/2024\/05\/02\/organizing\/jasper2024-04-26\/><\/div>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":488,"height":650,"file":"2024\/04\/Jasper2024-04-26.jpg","filesize":293668,"sizes":{"medium":{"file":"Jasper2024-04-26-338x450.jpg","width":338,"height":450,"filesize":97821,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/04\/Jasper2024-04-26-338x450.jpg"},"thumbnail":{"file":"Jasper2024-04-26-113x150.jpg","width":113,"height":150,"filesize":28493,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/04\/Jasper2024-04-26-113x150.jpg"},"full":{"file":"Jasper2024-04-26.jpg","width":488,"height":650,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/04\/Jasper2024-04-26.jpg"}},"image_meta":{"aperture":"1.5","credit":"","camera":"iPhone 14 Plus","caption":"","created_timestamp":"1714146568","copyright":"","focal_length":"5.7","iso":"400","shutter_speed":"0.025","title":"","orientation":"1","keywords":[]}},"post":11796,"source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/04\/Jasper2024-04-26.jpg","_links":{"self":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media\/11807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/comments?post=11807"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":11796,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/posts\/11796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}