{"id":12428,"date":"2024-08-13T23:12:42","date_gmt":"2024-08-14T04:12:42","guid":{"rendered":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/08\/legoliondenverzoo.jpg"},"modified":"2024-08-14T14:21:13","modified_gmt":"2024-08-14T19:21:13","slug":"legoliondenverzoo","status":"inherit","type":"attachment","link":"https:\/\/www.debslunch.com\/blog\/2024\/08\/14\/birthday-week\/legoliondenverzoo\/","title":{"rendered":"legoliondenverzoo"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":{"0":"entry","1":"attachment","2":"publish","3":"author-ds83473gmail-com","4":"post-12428","6":"status-inherit"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/08\/legoliondenverzoo.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"352\" height=\"450\" src=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/08\/legoliondenverzoo-352x450.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/08\/legoliondenverzoo-352x450.jpg 352w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/08\/legoliondenverzoo-117x150.jpg 117w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/08\/legoliondenverzoo.jpg 509w\" sizes=\"auto, (max-width: 352px) 100vw, 352px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Lego lion<\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" data-url=https:\/\/www.debslunch.com\/blog\/2024\/08\/14\/birthday-week\/legoliondenverzoo\/><\/div>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":509,"height":650,"file":"2024\/08\/legoliondenverzoo.jpg","filesize":523364,"sizes":{"medium":{"file":"legoliondenverzoo-352x450.jpg","width":352,"height":450,"filesize":157366,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/08\/legoliondenverzoo-352x450.jpg"},"thumbnail":{"file":"legoliondenverzoo-117x150.jpg","width":117,"height":150,"filesize":32019,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/08\/legoliondenverzoo-117x150.jpg"},"full":{"file":"legoliondenverzoo.jpg","width":509,"height":650,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/08\/legoliondenverzoo.jpg"}},"image_meta":{"aperture":"1.5","credit":"","camera":"iPhone 14 Plus","caption":"","created_timestamp":"1722696424","copyright":"","focal_length":"5.7","iso":"50","shutter_speed":"0.0010183299389002","title":"","orientation":"1","keywords":[]}},"post":12405,"source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2024\/08\/legoliondenverzoo.jpg","_links":{"self":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media\/12428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/comments?post=12428"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":12405,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/posts\/12405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}