{"id":13782,"date":"2025-05-19T16:48:16","date_gmt":"2025-05-19T21:48:16","guid":{"rendered":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2025\/05\/jaspercookiestamps3.jpg"},"modified":"2025-05-23T15:17:13","modified_gmt":"2025-05-23T20:17:13","slug":"jaspercookiestamps3","status":"inherit","type":"attachment","link":"https:\/\/www.debslunch.com\/blog\/2025\/05\/23\/an-all-play-weekend\/jaspercookiestamps3\/","title":{"rendered":"jaspercookiestamps3"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":{"0":"entry","1":"attachment","2":"publish","3":"author-ds83473gmail-com","4":"post-13782","6":"status-inherit"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2025\/05\/jaspercookiestamps3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"488\" height=\"650\" src=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2025\/05\/jaspercookiestamps3.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2025\/05\/jaspercookiestamps3.jpg 488w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2025\/05\/jaspercookiestamps3-113x150.jpg 113w\" sizes=\"auto, (max-width: 488px) 100vw, 488px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Playdough and cookie stamps<\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" data-url=https:\/\/www.debslunch.com\/blog\/2025\/05\/23\/an-all-play-weekend\/jaspercookiestamps3\/><\/div>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":488,"height":650,"file":"2025\/05\/jaspercookiestamps3.jpg","filesize":261050,"sizes":{"thumbnail":{"file":"jaspercookiestamps3-113x150.jpg","width":113,"height":150,"filesize":21103,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2025\/05\/jaspercookiestamps3-113x150.jpg"},"full":{"file":"jaspercookiestamps3.jpg","width":488,"height":650,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2025\/05\/jaspercookiestamps3.jpg"}},"image_meta":{"aperture":"1.5","credit":"","camera":"iPhone 14 Plus","caption":"","created_timestamp":"1747209922","copyright":"","focal_length":"5.7","iso":"500","shutter_speed":"0.025","title":"","orientation":"1","keywords":[]}},"post":13760,"source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2025\/05\/jaspercookiestamps3.jpg","_links":{"self":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media\/13782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/comments?post=13782"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":13760,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/posts\/13760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}