{"id":13868,"date":"2025-06-10T14:34:03","date_gmt":"2025-06-10T19:34:03","guid":{"rendered":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2025\/06\/flamingosvilas2.jpg"},"modified":"2025-06-11T15:27:41","modified_gmt":"2025-06-11T20:27:41","slug":"flamingosvilas2","status":"inherit","type":"attachment","link":"https:\/\/www.debslunch.com\/blog\/2025\/06\/11\/minor-mishaps\/flamingosvilas2\/","title":{"rendered":"flamingosvilas2"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":{"0":"entry","1":"attachment","2":"publish","3":"author-ds83473gmail-com","4":"post-13868","6":"status-inherit"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2025\/06\/flamingosvilas2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"535\" height=\"650\" src=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2025\/06\/flamingosvilas2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2025\/06\/flamingosvilas2.jpg 535w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2025\/06\/flamingosvilas2-123x150.jpg 123w\" sizes=\"auto, (max-width: 535px) 100vw, 535px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>we went someplace  <\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" data-url=https:\/\/www.debslunch.com\/blog\/2025\/06\/11\/minor-mishaps\/flamingosvilas2\/><\/div>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":535,"height":650,"file":"2025\/06\/flamingosvilas2.jpg","filesize":519628,"sizes":{"thumbnail":{"file":"flamingosvilas2-123x150.jpg","width":123,"height":150,"filesize":24180,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2025\/06\/flamingosvilas2-123x150.jpg"},"full":{"file":"flamingosvilas2.jpg","width":535,"height":650,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2025\/06\/flamingosvilas2.jpg"}},"image_meta":{"aperture":"1.5","credit":"","camera":"iPhone 14 Plus","caption":"","created_timestamp":"1749050669","copyright":"","focal_length":"5.7","iso":"50","shutter_speed":"0.00046189376443418","title":"","orientation":"1","keywords":[]}},"post":13845,"source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2025\/06\/flamingosvilas2.jpg","_links":{"self":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media\/13868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/comments?post=13868"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":13845,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/posts\/13845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}