{"id":4184,"date":"2019-01-22T19:10:37","date_gmt":"2019-01-23T01:10:37","guid":{"rendered":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/01\/apron2.jpg"},"modified":"2019-01-22T19:11:09","modified_gmt":"2019-01-23T01:11:09","slug":"apron2","status":"inherit","type":"attachment","link":"https:\/\/www.debslunch.com\/blog\/2019\/01\/22\/mlk-day-in-seattle\/apron2\/","title":{"rendered":"apron2"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":{"0":"entry","1":"attachment","2":"publish","3":"author-ds83473gmail-com","4":"post-4184","6":"status-inherit"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/01\/apron2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"390\" height=\"450\" src=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/01\/apron2-390x450.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/01\/apron2-390x450.jpg 390w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/01\/apron2-130x150.jpg 130w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/01\/apron2.jpg 563w\" sizes=\"auto, (max-width: 390px) 100vw, 390px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>On the dining table<\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" data-url=https:\/\/www.debslunch.com\/blog\/2019\/01\/22\/mlk-day-in-seattle\/apron2\/><\/div>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":563,"height":650,"file":"2019\/01\/apron2.jpg","sizes":{"thumbnail":{"file":"apron2-130x150.jpg","width":130,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/01\/apron2-130x150.jpg"},"medium":{"file":"apron2-390x450.jpg","width":390,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/01\/apron2-390x450.jpg"},"full":{"file":"apron2.jpg","width":563,"height":650,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/01\/apron2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":4181,"source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/01\/apron2.jpg","_links":{"self":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media\/4184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/comments?post=4184"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":4181,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/posts\/4181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}