{"id":5542,"date":"2019-10-21T11:02:03","date_gmt":"2019-10-21T16:02:03","guid":{"rendered":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/10\/colectivomissedyoga.jpg"},"modified":"2019-10-21T12:23:31","modified_gmt":"2019-10-21T17:23:31","slug":"colectivomissedyoga","status":"inherit","type":"attachment","link":"https:\/\/www.debslunch.com\/blog\/2019\/10\/21\/still-not-keeping-up-very-well\/colectivomissedyoga\/","title":{"rendered":"colectivomissedyoga"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":{"0":"entry","1":"attachment","2":"publish","3":"author-ds83473gmail-com","4":"post-5542","6":"status-inherit"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/10\/colectivomissedyoga.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"410\" height=\"450\" src=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/10\/colectivomissedyoga-410x450.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/10\/colectivomissedyoga-410x450.jpg 410w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/10\/colectivomissedyoga-137x150.jpg 137w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/10\/colectivomissedyoga.jpg 592w\" sizes=\"auto, (max-width: 410px) 100vw, 410px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Pretty latte that made me too late for yoga<\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" data-url=https:\/\/www.debslunch.com\/blog\/2019\/10\/21\/still-not-keeping-up-very-well\/colectivomissedyoga\/><\/div>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":592,"height":650,"file":"2019\/10\/colectivomissedyoga.jpg","sizes":{"thumbnail":{"file":"colectivomissedyoga-137x150.jpg","width":137,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/10\/colectivomissedyoga-137x150.jpg"},"medium":{"file":"colectivomissedyoga-410x450.jpg","width":410,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/10\/colectivomissedyoga-410x450.jpg"},"full":{"file":"colectivomissedyoga.jpg","width":592,"height":650,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/10\/colectivomissedyoga.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":5535,"source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2019\/10\/colectivomissedyoga.jpg","_links":{"self":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media\/5542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/comments?post=5542"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":5535,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/posts\/5535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}