{"id":6439,"date":"2020-05-16T13:56:40","date_gmt":"2020-05-16T18:56:40","guid":{"rendered":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/05\/cookedasparagus.jpg"},"modified":"2020-05-16T13:59:00","modified_gmt":"2020-05-16T18:59:00","slug":"cookedasparagus","status":"inherit","type":"attachment","link":"https:\/\/www.debslunch.com\/blog\/2020\/05\/16\/how-to-survive-the-pandemic\/cookedasparagus\/","title":{"rendered":"cookedasparagus"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":{"0":"entry","1":"attachment","2":"publish","3":"author-ds83473gmail-com","4":"post-6439","6":"status-inherit"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/05\/cookedasparagus.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"338\" height=\"450\" src=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/05\/cookedasparagus-338x450.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/05\/cookedasparagus-338x450.jpg 338w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/05\/cookedasparagus-113x150.jpg 113w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/05\/cookedasparagus.jpg 488w\" sizes=\"auto, (max-width: 338px) 100vw, 338px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>cooked asparagus that didn&#8217;t go in the quiche<\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" data-url=https:\/\/www.debslunch.com\/blog\/2020\/05\/16\/how-to-survive-the-pandemic\/cookedasparagus\/><\/div>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":488,"height":650,"file":"2020\/05\/cookedasparagus.jpg","sizes":{"medium":{"file":"cookedasparagus-338x450.jpg","width":338,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/05\/cookedasparagus-338x450.jpg"},"thumbnail":{"file":"cookedasparagus-113x150.jpg","width":113,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/05\/cookedasparagus-113x150.jpg"},"full":{"file":"cookedasparagus.jpg","width":488,"height":650,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/05\/cookedasparagus.jpg"}},"image_meta":{"aperture":"1.8","credit":"","camera":"iPhone 8 Plus","caption":"","created_timestamp":"1589638851","copyright":"","focal_length":"3.99","iso":"125","shutter_speed":"0.25","title":"","orientation":"1","keywords":[]}},"post":6428,"source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/05\/cookedasparagus.jpg","_links":{"self":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media\/6439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/comments?post=6439"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":6428,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/posts\/6428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}