{"id":6517,"date":"2020-06-09T21:03:56","date_gmt":"2020-06-10T02:03:56","guid":{"rendered":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/06\/chilaquiles.jpg"},"modified":"2020-06-09T21:10:42","modified_gmt":"2020-06-10T02:10:42","slug":"chilaquiles","status":"inherit","type":"attachment","link":"https:\/\/www.debslunch.com\/blog\/2020\/06\/09\/perchance-to-dream\/chilaquiles\/","title":{"rendered":"chilaquiles"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":{"0":"entry","1":"attachment","2":"publish","3":"author-ds83473gmail-com","4":"post-6517","6":"status-inherit"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/06\/chilaquiles.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"450\" src=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/06\/chilaquiles-370x450.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/06\/chilaquiles-370x450.jpg 370w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/06\/chilaquiles-123x150.jpg 123w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/06\/chilaquiles.jpg 535w\" sizes=\"auto, (max-width: 370px) 100vw, 370px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Chilaquiles for Sunday brunch<\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" data-url=https:\/\/www.debslunch.com\/blog\/2020\/06\/09\/perchance-to-dream\/chilaquiles\/><\/div>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":535,"height":650,"file":"2020\/06\/chilaquiles.jpg","sizes":{"medium":{"file":"chilaquiles-370x450.jpg","width":370,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/06\/chilaquiles-370x450.jpg"},"thumbnail":{"file":"chilaquiles-123x150.jpg","width":123,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/06\/chilaquiles-123x150.jpg"},"full":{"file":"chilaquiles.jpg","width":535,"height":650,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/06\/chilaquiles.jpg"}},"image_meta":{"aperture":"1.8","credit":"","camera":"iPhone 8 Plus","caption":"","created_timestamp":"1591551927","copyright":"","focal_length":"3.99","iso":"100","shutter_speed":"0.25","title":"","orientation":"1","keywords":[]}},"post":6502,"source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2020\/06\/chilaquiles.jpg","_links":{"self":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media\/6517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/comments?post=6517"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":6502,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/posts\/6502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}