{"id":8998,"date":"2022-06-29T21:37:34","date_gmt":"2022-06-30T02:37:34","guid":{"rendered":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/tuestouristbrekkie.jpg"},"modified":"2022-06-29T21:39:25","modified_gmt":"2022-06-30T02:39:25","slug":"tuestouristbrekkie","status":"inherit","type":"attachment","link":"https:\/\/www.debslunch.com\/blog\/2022\/06\/29\/first-library-conference-in-3-years\/tuestouristbrekkie\/","title":{"rendered":"tuestouristbrekkie"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":{"0":"entry","1":"attachment","2":"publish","3":"author-ds83473gmail-com","4":"post-8998","6":"status-inherit"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/tuestouristbrekkie.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"338\" height=\"450\" src=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/tuestouristbrekkie-338x450.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/tuestouristbrekkie-338x450.jpg 338w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/tuestouristbrekkie-113x150.jpg 113w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/tuestouristbrekkie.jpg 488w\" sizes=\"auto, (max-width: 338px) 100vw, 338px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>goat cheese and tomato tartine at Tatte<\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" data-url=https:\/\/www.debslunch.com\/blog\/2022\/06\/29\/first-library-conference-in-3-years\/tuestouristbrekkie\/><\/div>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":488,"height":650,"file":"2022\/06\/tuestouristbrekkie.jpg","filesize":246176,"sizes":{"medium":{"file":"tuestouristbrekkie-338x450.jpg","width":338,"height":450,"filesize":76811,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/tuestouristbrekkie-338x450.jpg"},"thumbnail":{"file":"tuestouristbrekkie-113x150.jpg","width":113,"height":150,"filesize":22242,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/tuestouristbrekkie-113x150.jpg"},"full":{"file":"tuestouristbrekkie.jpg","width":488,"height":650,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/tuestouristbrekkie.jpg"}},"image_meta":{"aperture":"1.8","credit":"","camera":"iPhone 8 Plus","caption":"","created_timestamp":"1656429036","copyright":"","focal_length":"3.99","iso":"20","shutter_speed":"0.0029585798816568","title":"","orientation":"1","keywords":[]}},"post":8986,"source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/tuestouristbrekkie.jpg","_links":{"self":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media\/8998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/comments?post=8998"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":8986,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/posts\/8986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}