{"id":9005,"date":"2022-06-29T21:37:41","date_gmt":"2022-06-30T02:37:41","guid":{"rendered":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/typewritereraser.jpg"},"modified":"2022-06-29T21:51:03","modified_gmt":"2022-06-30T02:51:03","slug":"typewritereraser","status":"inherit","type":"attachment","link":"https:\/\/www.debslunch.com\/blog\/2022\/06\/29\/first-library-conference-in-3-years\/typewritereraser\/","title":{"rendered":"typewritereraser"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":{"0":"entry","1":"attachment","2":"publish","3":"author-ds83473gmail-com","4":"post-9005","6":"status-inherit"},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/typewritereraser.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"338\" height=\"450\" src=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/typewritereraser-338x450.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/typewritereraser-338x450.jpg 338w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/typewritereraser-113x150.jpg 113w, https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/typewritereraser.jpg 488w\" sizes=\"auto, (max-width: 338px) 100vw, 338px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Claes Oldenberg eraser<\/p>\n<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" data-url=https:\/\/www.debslunch.com\/blog\/2022\/06\/29\/first-library-conference-in-3-years\/typewritereraser\/><\/div>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":488,"height":650,"file":"2022\/06\/typewritereraser.jpg","filesize":396471,"sizes":{"medium":{"file":"typewritereraser-338x450.jpg","width":338,"height":450,"filesize":120420,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/typewritereraser-338x450.jpg"},"thumbnail":{"file":"typewritereraser-113x150.jpg","width":113,"height":150,"filesize":27920,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/typewritereraser-113x150.jpg"},"full":{"file":"typewritereraser.jpg","width":488,"height":650,"mime_type":"image\/jpeg","source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/typewritereraser.jpg"}},"image_meta":{"aperture":"1.8","credit":"","camera":"iPhone 8 Plus","caption":"","created_timestamp":"1656439849","copyright":"","focal_length":"3.99","iso":"20","shutter_speed":"0.0014164305949008","title":"","orientation":"1","keywords":[]}},"post":8986,"source_url":"https:\/\/www.debslunch.com\/blog\/wp-content\/uploads\/2022\/06\/typewritereraser.jpg","_links":{"self":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media\/9005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/comments?post=9005"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":8986,"href":"https:\/\/www.debslunch.com\/blog\/wp-json\/wp\/v2\/posts\/8986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}